
{"id":923,"date":"2021-12-21T20:17:15","date_gmt":"2021-12-21T20:17:15","guid":{"rendered":"https:\/\/residencelasalamandre.eu\/accommodation\/chambre-tournesol\/"},"modified":"2023-03-28T09:47:25","modified_gmt":"2023-03-28T09:47:25","slug":"chambre-tournesol","status":"publish","type":"mphb_room_type","link":"https:\/\/residencelasalamandre.eu\/fr\/accommodation\/chambre-tournesol\/","title":{"rendered":"Chambre Tournesol"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row css=\u00a0\u00bb.vc_custom_1636058040151{padding-top: 50px !important;padding-bottom: 100px !important;}\u00a0\u00bb][vc_column css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb width=\u00a0\u00bb5\/12&Prime;][vc_column_text]<\/p>\n<div class=\"uk-section-default uk-section uk-section-small\">\n<h1>Chambre Tournesol<\/h1>\n<p>Dans cette belle chambre ensoleill\u00e9e, tout tourne autour du tournesol (tournesol) et de mai \u00e0 septembre, les tournesols ext\u00e9rieurs apportent une note de gaiet\u00e9 suppl\u00e9mentaire. La chambre est au rez-de-chauss\u00e9e. Vous pouvez vous promener de cette pi\u00e8ce \u00e0 travers le toit jusqu&rsquo;\u00e0 la piscine, la belle terrasse et la salle \u00e0 manger sans barri\u00e8res. Dans cette chambre, les deux lits boxspring merveilleusement endormis peuvent \u00eatre facilement s\u00e9par\u00e9s et cela n&rsquo;affecte pas l&rsquo;espace de la pi\u00e8ce. Un WC, douche et lavabo privatifs et un espace de travail privatif et une connexion USB. Deux fauteuils et la possibilit\u00e9 de se faire une tasse de th\u00e9 ou de caf\u00e9 et avec vue sur la piscine et le magnifique coucher de soleil le soir. Une chambre pour vous faire plaisir.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>Le d\u00eener est disponible sur demande avec un pr\u00e9avis de 24 heures. En haute saison, ce n&rsquo;est pas possible les samedis et dimanches.[\/vc_column_text][\/vc_column][vc_column width=\u00a0\u00bb7\/12&Prime;][vc_gallery interval=\u00a0\u00bb0&Prime; images=\u00a0\u00bb1990,1987,2002,1999,1996,1984,1993,1981&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb css_animation=\u00a0\u00bbfadeInRight\u00a0\u00bb][\/vc_column][\/vc_row][vc_row full_width=\u00a0\u00bbstretch_row\u00a0\u00bb css=\u00a0\u00bb.vc_custom_1636062004418{padding-top: 100px !important;padding-bottom: 100px !important;background-color: #ffffff !important;}\u00a0\u00bb][vc_column css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][vc_column_text]<\/p>\n<h2 class=\"uk-h5 uk-heading-line uk-scrollspy-inview uk-animation-fade\">D\u00e9coration de la chambre<\/h2>\n<table>\n<tbody>\n<tr>\n<td>Lit<\/td>\n<td>2 sommiers simples (90\u00d7200 cm)<\/td>\n<\/tr>\n<tr>\n<td>Conception<\/td>\n<td>2 fauteuils et une table<\/td>\n<\/tr>\n<tr>\n<td>Salle de bains<\/td>\n<td>Salle de bain avec meuble vasque, douche \u00e0 l&rsquo;italienne et WC suspendu<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>[\/vc_column_text][\/vc_column][vc_column css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb width=\u00a0\u00bb1\/2&Prime;][\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=\u00a0\u00bb.vc_custom_1636058040151{padding-top: 50px !important;padding-bottom: 100px !important;}\u00a0\u00bb][vc_column css_animation=\u00a0\u00bbfadeIn\u00a0\u00bb width=\u00a0\u00bb5\/12&Prime;][vc_column_text] Chambre Tournesol Dans cette belle chambre ensoleill\u00e9e, tout tourne autour du tournesol (tournesol) et de mai \u00e0 septembre, les tournesols ext\u00e9rieurs apportent une note de gaiet\u00e9 suppl\u00e9mentaire. La chambre est au rez-de-chauss\u00e9e. Vous pouvez vous promener de cette pi\u00e8ce \u00e0 travers le toit jusqu&rsquo;\u00e0 la piscine, la [&hellip;]<\/p>\n","protected":false},"featured_media":407,"menu_order":1,"comment_status":"open","ping_status":"closed","template":"","mphb_room_type_category":[],"mphb_room_type_tag":[],"mphb_room_type_facility":[],"class_list":["post-923","mphb_room_type","type-mphb_room_type","status-publish","has-post-thumbnail","hentry","mphb-room-type-adults-2","mphb-room-type-children-1","has-taxes-and-fees"],"_links":{"self":[{"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/mphb_room_type\/923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/mphb_room_type"}],"about":[{"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/types\/mphb_room_type"}],"replies":[{"embeddable":true,"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/comments?post=923"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/media\/407"}],"wp:attachment":[{"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/media?parent=923"}],"wp:term":[{"taxonomy":"mphb_room_type_category","embeddable":true,"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/mphb_room_type_category?post=923"},{"taxonomy":"mphb_room_type_tag","embeddable":true,"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/mphb_room_type_tag?post=923"},{"taxonomy":"mphb_room_type_facility","embeddable":true,"href":"https:\/\/residencelasalamandre.eu\/fr\/wp-json\/wp\/v2\/mphb_room_type_facility?post=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}